
{"id":51661,"date":"2022-03-27T13:58:41","date_gmt":"2022-03-27T11:58:41","guid":{"rendered":"https:\/\/tierpark-bern.ch\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/"},"modified":"2025-04-09T09:33:57","modified_gmt":"2025-04-09T07:33:57","slug":"zwei-kleine-zwergziegen-erblickten-das-licht-der-welt","status":"publish","type":"post","link":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/","title":{"rendered":"Zwei kleine Zwergziegen im Kinderzoo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h2>Am 27. M\u00e4rz 2022 erblickten zwei kleine Zwergziegen das Licht der Welt<\/h2>\n<p>Im Kinderzoo vom Tierpark sind zwei Jungtiere bei den Zwergziegen geboren.\u00a0Im Abstand von acht Monaten wirft eine Geiss nach einer Tragzeit von 150 bis 160 Tagen meisst 1 bis 2 Junge. Das Jungtier wird Ziegenkitz, Ziegenlamm oder Geisslein genannt. Bei uns in der Schweiz nennt man es Gitzi.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Am 27. M\u00e4rz 2022 erblickten zwei kleine Zwergziegen das Licht der Welt.<\/p>\n","protected":false},"author":1,"featured_media":26257,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[305],"tags":[339],"zoo-type":[383],"animal-list":[734],"class_list":["post-51661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-zwergziege-en","zoo-type-daehlhoelzli","animal-list-zwergziege-en"],"acf":[],"yoast_head":"<title>Zwei kleine Zwergziegen im Kinderzoo | Tierpark Bern<\/title>\n<meta name=\"description\" content=\"Im Kinderzoo vom Tierpark sind zwei Jungtiere bei den Zwergziegen geboren.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zwei kleine Zwergziegen im Kinderzoo | Tierpark Bern\" \/>\n<meta property=\"og:description\" content=\"Im Kinderzoo vom Tierpark sind zwei Jungtiere bei den Zwergziegen geboren.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/\" \/>\n<meta property=\"og:site_name\" content=\"Tierpark Bern\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tierparkbern\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-27T11:58:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-09T07:33:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2022\/03\/zwergziegen-jungtier-2022-bern-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"998\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#\/schema\/person\/fc8c06f92d4096baa065d0e5a8a5ffd7\"},\"headline\":\"Zwei kleine Zwergziegen im Kinderzoo\",\"datePublished\":\"2022-03-27T11:58:41+00:00\",\"dateModified\":\"2025-04-09T07:33:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/\"},\"wordCount\":75,\"publisher\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2022\/03\/zwergziegen-jungtier-2022-bern-2.jpg\",\"keywords\":[\"Dwarf goat\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/\",\"url\":\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/\",\"name\":\"Zwei kleine Zwergziegen im Kinderzoo | Tierpark Bern\",\"isPartOf\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2022\/03\/zwergziegen-jungtier-2022-bern-2.jpg\",\"datePublished\":\"2022-03-27T11:58:41+00:00\",\"dateModified\":\"2025-04-09T07:33:57+00:00\",\"description\":\"Im Kinderzoo vom Tierpark sind zwei Jungtiere bei den Zwergziegen geboren.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#primaryimage\",\"url\":\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2022\/03\/zwergziegen-jungtier-2022-bern-2.jpg\",\"contentUrl\":\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2022\/03\/zwergziegen-jungtier-2022-bern-2.jpg\",\"width\":1500,\"height\":998},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/tierpark-bern.ch\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zwei kleine Zwergziegen im Kinderzoo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#website\",\"url\":\"https:\/\/tierpark-bern.ch\/en\/\",\"name\":\"Tierpark Bern\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tierpark-bern.ch\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#organization\",\"name\":\"Tierpark Bern | D\u00e4hlh\u00f6lzli + B\u00e4renPark\",\"alternateName\":\"Tierpark Bern\",\"url\":\"https:\/\/tierpark-bern.ch\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2024\/04\/tierpark-bern-696x696-1.jpg\",\"contentUrl\":\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2024\/04\/tierpark-bern-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"Tierpark Bern | D\u00e4hlh\u00f6lzli + B\u00e4renPark\"},\"image\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tierparkbern\/\",\"https:\/\/x.com\/tierparkbern\",\"https:\/\/www.instagram.com\/tierparkbern\/\"]}]}<\/script>","yoast_head_json":{"title":"Zwei kleine Zwergziegen im Kinderzoo | Tierpark Bern","description":"Im Kinderzoo vom Tierpark sind zwei Jungtiere bei den Zwergziegen geboren.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/","og_locale":"en_US","og_type":"article","og_title":"Zwei kleine Zwergziegen im Kinderzoo | Tierpark Bern","og_description":"Im Kinderzoo vom Tierpark sind zwei Jungtiere bei den Zwergziegen geboren.\u00a0","og_url":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/","og_site_name":"Tierpark Bern","article_publisher":"https:\/\/www.facebook.com\/tierparkbern\/","article_published_time":"2022-03-27T11:58:41+00:00","article_modified_time":"2025-04-09T07:33:57+00:00","og_image":[{"width":1500,"height":998,"url":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2022\/03\/zwergziegen-jungtier-2022-bern-2.jpg","type":"image\/jpeg"}],"author":"Admin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#article","isPartOf":{"@id":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/"},"author":{"name":"Admin","@id":"https:\/\/tierpark-bern.ch\/en\/#\/schema\/person\/fc8c06f92d4096baa065d0e5a8a5ffd7"},"headline":"Zwei kleine Zwergziegen im Kinderzoo","datePublished":"2022-03-27T11:58:41+00:00","dateModified":"2025-04-09T07:33:57+00:00","mainEntityOfPage":{"@id":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/"},"wordCount":75,"publisher":{"@id":"https:\/\/tierpark-bern.ch\/en\/#organization"},"image":{"@id":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#primaryimage"},"thumbnailUrl":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2022\/03\/zwergziegen-jungtier-2022-bern-2.jpg","keywords":["Dwarf goat"],"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/","url":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/","name":"Zwei kleine Zwergziegen im Kinderzoo | Tierpark Bern","isPartOf":{"@id":"https:\/\/tierpark-bern.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#primaryimage"},"image":{"@id":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#primaryimage"},"thumbnailUrl":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2022\/03\/zwergziegen-jungtier-2022-bern-2.jpg","datePublished":"2022-03-27T11:58:41+00:00","dateModified":"2025-04-09T07:33:57+00:00","description":"Im Kinderzoo vom Tierpark sind zwei Jungtiere bei den Zwergziegen geboren.\u00a0","breadcrumb":{"@id":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#primaryimage","url":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2022\/03\/zwergziegen-jungtier-2022-bern-2.jpg","contentUrl":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2022\/03\/zwergziegen-jungtier-2022-bern-2.jpg","width":1500,"height":998},{"@type":"BreadcrumbList","@id":"https:\/\/tierpark-bern.ch\/en\/news\/zwei-kleine-zwergziegen-erblickten-das-licht-der-welt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tierpark-bern.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Zwei kleine Zwergziegen im Kinderzoo"}]},{"@type":"WebSite","@id":"https:\/\/tierpark-bern.ch\/en\/#website","url":"https:\/\/tierpark-bern.ch\/en\/","name":"Tierpark Bern","description":"","publisher":{"@id":"https:\/\/tierpark-bern.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tierpark-bern.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tierpark-bern.ch\/en\/#organization","name":"Tierpark Bern | D\u00e4hlh\u00f6lzli + B\u00e4renPark","alternateName":"Tierpark Bern","url":"https:\/\/tierpark-bern.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tierpark-bern.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2024\/04\/tierpark-bern-696x696-1.jpg","contentUrl":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2024\/04\/tierpark-bern-696x696-1.jpg","width":696,"height":696,"caption":"Tierpark Bern | D\u00e4hlh\u00f6lzli + B\u00e4renPark"},"image":{"@id":"https:\/\/tierpark-bern.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tierparkbern\/","https:\/\/x.com\/tierparkbern","https:\/\/www.instagram.com\/tierparkbern\/"]}]}},"_links":{"self":[{"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/posts\/51661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/comments?post=51661"}],"version-history":[{"count":0,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/posts\/51661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/media\/26257"}],"wp:attachment":[{"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/media?parent=51661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/categories?post=51661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/tags?post=51661"},{"taxonomy":"zoo-type","embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/zoo-type?post=51661"},{"taxonomy":"animal-list","embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/animal-list?post=51661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}