
{"id":55548,"date":"2023-05-19T13:56:37","date_gmt":"2023-05-19T11:56:37","guid":{"rendered":"https:\/\/tierpark-bern.ch\/news\/drei-jungtiere-bei-den-woelfen\/"},"modified":"2025-04-09T09:29:53","modified_gmt":"2025-04-09T07:29:53","slug":"drei-jungtiere-bei-den-woelfen","status":"publish","type":"post","link":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/","title":{"rendered":"Drei Jungtiere bei den W\u00f6lfen"},"content":{"rendered":"<p>Unser Wolf-Zuchtpaar hat am 23. April 2023 zum zweiten Mal Nachwuchs. Die drei Welpen mit ihrem feinen, dunklen Fell haben bereits die Augen ge\u00f6ffnet und wagen die ersten Schritte vor die H\u00f6hle.<\/p>\n<p>Dem adulten Zuchtpaar merkt man die Erfahrung an, sind sie doch um einiges entspannter als beim ersten Mal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unser Wolf-Zuchtpaar hat am 23. April 2023 zum 2. Mal Nachwuchs.<\/p>\n","protected":false},"author":1,"featured_media":55537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[305],"tags":[317],"zoo-type":[383],"animal-list":[728],"class_list":["post-55548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-europaeischer-wolf-en","zoo-type-daehlhoelzli","animal-list-europaeischer-wolf-en"],"acf":[],"yoast_head":"<title>Drei Jungtiere bei den W\u00f6lfen | Tierpark Bern<\/title>\n<meta name=\"description\" content=\"Unser Wolf-Zuchtpaar hat am 23. April 2023 zum 2. Mal Nachwuchs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drei Jungtiere bei den W\u00f6lfen | Tierpark Bern\" \/>\n<meta property=\"og:description\" content=\"Unser Wolf-Zuchtpaar hat am 23. April 2023 zum 2. Mal Nachwuchs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/\" \/>\n<meta property=\"og:site_name\" content=\"Tierpark Bern\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tierparkbern\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-19T11:56:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-09T07:29:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2023\/05\/T4A8227-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#\/schema\/person\/fc8c06f92d4096baa065d0e5a8a5ffd7\"},\"headline\":\"Drei Jungtiere bei den W\u00f6lfen\",\"datePublished\":\"2023-05-19T11:56:37+00:00\",\"dateModified\":\"2025-04-09T07:29:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/\"},\"wordCount\":56,\"publisher\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2023\/05\/T4A8227-min.jpg\",\"keywords\":[\"European wolf\"],\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/\",\"url\":\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/\",\"name\":\"Drei Jungtiere bei den W\u00f6lfen | Tierpark Bern\",\"isPartOf\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2023\/05\/T4A8227-min.jpg\",\"datePublished\":\"2023-05-19T11:56:37+00:00\",\"dateModified\":\"2025-04-09T07:29:53+00:00\",\"description\":\"Unser Wolf-Zuchtpaar hat am 23. April 2023 zum 2. Mal Nachwuchs.\",\"breadcrumb\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#primaryimage\",\"url\":\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2023\/05\/T4A8227-min.jpg\",\"contentUrl\":\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2023\/05\/T4A8227-min.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Nahaufnahme von einem Wolfs-Jungtier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/tierpark-bern.ch\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Drei Jungtiere bei den W\u00f6lfen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#website\",\"url\":\"https:\/\/tierpark-bern.ch\/en\/\",\"name\":\"Tierpark Bern\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tierpark-bern.ch\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#organization\",\"name\":\"Tierpark Bern | D\u00e4hlh\u00f6lzli + B\u00e4renPark\",\"alternateName\":\"Tierpark Bern\",\"url\":\"https:\/\/tierpark-bern.ch\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2024\/04\/tierpark-bern-696x696-1.jpg\",\"contentUrl\":\"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2024\/04\/tierpark-bern-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"Tierpark Bern | D\u00e4hlh\u00f6lzli + B\u00e4renPark\"},\"image\":{\"@id\":\"https:\/\/tierpark-bern.ch\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/tierparkbern\/\",\"https:\/\/x.com\/tierparkbern\",\"https:\/\/www.instagram.com\/tierparkbern\/\"]}]}<\/script>","yoast_head_json":{"title":"Drei Jungtiere bei den W\u00f6lfen | Tierpark Bern","description":"Unser Wolf-Zuchtpaar hat am 23. April 2023 zum 2. Mal Nachwuchs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/","og_locale":"en_US","og_type":"article","og_title":"Drei Jungtiere bei den W\u00f6lfen | Tierpark Bern","og_description":"Unser Wolf-Zuchtpaar hat am 23. April 2023 zum 2. Mal Nachwuchs.","og_url":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/","og_site_name":"Tierpark Bern","article_publisher":"https:\/\/www.facebook.com\/tierparkbern\/","article_published_time":"2023-05-19T11:56:37+00:00","article_modified_time":"2025-04-09T07:29:53+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2023\/05\/T4A8227-min.jpg","type":"image\/jpeg"}],"author":"Admin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#article","isPartOf":{"@id":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/"},"author":{"name":"Admin","@id":"https:\/\/tierpark-bern.ch\/en\/#\/schema\/person\/fc8c06f92d4096baa065d0e5a8a5ffd7"},"headline":"Drei Jungtiere bei den W\u00f6lfen","datePublished":"2023-05-19T11:56:37+00:00","dateModified":"2025-04-09T07:29:53+00:00","mainEntityOfPage":{"@id":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/"},"wordCount":56,"publisher":{"@id":"https:\/\/tierpark-bern.ch\/en\/#organization"},"image":{"@id":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#primaryimage"},"thumbnailUrl":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2023\/05\/T4A8227-min.jpg","keywords":["European wolf"],"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/","url":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/","name":"Drei Jungtiere bei den W\u00f6lfen | Tierpark Bern","isPartOf":{"@id":"https:\/\/tierpark-bern.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#primaryimage"},"image":{"@id":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#primaryimage"},"thumbnailUrl":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2023\/05\/T4A8227-min.jpg","datePublished":"2023-05-19T11:56:37+00:00","dateModified":"2025-04-09T07:29:53+00:00","description":"Unser Wolf-Zuchtpaar hat am 23. April 2023 zum 2. Mal Nachwuchs.","breadcrumb":{"@id":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#primaryimage","url":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2023\/05\/T4A8227-min.jpg","contentUrl":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2023\/05\/T4A8227-min.jpg","width":1200,"height":800,"caption":"Nahaufnahme von einem Wolfs-Jungtier"},{"@type":"BreadcrumbList","@id":"https:\/\/tierpark-bern.ch\/en\/news\/drei-jungtiere-bei-den-woelfen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tierpark-bern.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Drei Jungtiere bei den W\u00f6lfen"}]},{"@type":"WebSite","@id":"https:\/\/tierpark-bern.ch\/en\/#website","url":"https:\/\/tierpark-bern.ch\/en\/","name":"Tierpark Bern","description":"","publisher":{"@id":"https:\/\/tierpark-bern.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tierpark-bern.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tierpark-bern.ch\/en\/#organization","name":"Tierpark Bern | D\u00e4hlh\u00f6lzli + B\u00e4renPark","alternateName":"Tierpark Bern","url":"https:\/\/tierpark-bern.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tierpark-bern.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2024\/04\/tierpark-bern-696x696-1.jpg","contentUrl":"https:\/\/tierpark-bern.ch\/web\/app\/uploads\/2024\/04\/tierpark-bern-696x696-1.jpg","width":696,"height":696,"caption":"Tierpark Bern | D\u00e4hlh\u00f6lzli + B\u00e4renPark"},"image":{"@id":"https:\/\/tierpark-bern.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tierparkbern\/","https:\/\/x.com\/tierparkbern","https:\/\/www.instagram.com\/tierparkbern\/"]}]}},"_links":{"self":[{"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/posts\/55548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/comments?post=55548"}],"version-history":[{"count":0,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/posts\/55548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/media\/55537"}],"wp:attachment":[{"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/media?parent=55548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/categories?post=55548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/tags?post=55548"},{"taxonomy":"zoo-type","embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/zoo-type?post=55548"},{"taxonomy":"animal-list","embeddable":true,"href":"https:\/\/tierpark-bern.ch\/en\/wp-json\/wp\/v2\/animal-list?post=55548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}